{"id":3,"date":"2020-11-30T23:02:07","date_gmt":"2020-11-30T22:02:07","guid":{"rendered":"http:\/\/banti.it\/?page_id=3"},"modified":"2021-04-24T11:08:13","modified_gmt":"2021-04-24T09:08:13","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/banti.it\/it\/privacy-policy\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"<div id=\"dslc-main\">\n\t\t<div  class=\"dslc-modules-section \" style=\"padding-bottom:151px;padding-top:151px;\" data-section-id=\"9acc8a8262a\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"dslc-modules-section-wrapper dslc-clearfix\"><div class=\"dslc-modules-area dslc-col dslc-12-col dslc-last-col dslc-valign- \" data-size=\"12\" data-valign=\"\">\n\t\t<div id=\"dslc-module-627916614f9\" class=\"dslc-module-front dslc-module-DSLC_Text_Simple dslc-in-viewport-check dslc-in-viewport-anim-none  dslc-col dslc-12-col dslc-last-col  dslc-module-handle-like-regular \" data-module-id=\"627916614f9\" data-module=\"DSLC_Text_Simple\" data-dslc-module-size=\"12\" data-dslc-anim=\"none\" data-dslc-anim-delay=\"\" data-dslc-anim-duration=\"650\"  data-dslc-anim-easing=\"ease\" data-dslc-preset=\"none\" >\n\n\t\t\t\n\t\t\t\n\t\t\r\n\t\t<div class=\"dslc-text-module-content\">\r\n\t\t\t<h1 style=\"text-align: center;\"><strong><em>PRIVACY POLICY<\/em><\/strong><\/h1><p>La presente informativa viene resa in ossequio all'art. 13 del Regolamento 2016\/679 (GDPR), ai sensi dell'art. 13 del d.lgs. n. 196\/2003 (Codice in materia di protezione dei dati personali) agli utenti che accedono al sito web https:\/\/banti.it ed \u00e8 relativa a tutti i dati personali trattati secondo le modalit\u00e0 di seguito indicate.<\/p><p><strong><em>IL TITOLARE DEL TRATTAMENTO<\/em><\/strong><\/p><p>Il Titolare del trattamento dei dati personali raccolti \u00e8 Profilati Banti srl.<\/p><p><strong><em>DATI RACCOLTI<\/em><\/strong><\/p><p>I dati personali trattati sono raccolti in quanto forniti direttamente dall\u2019interessato o forniti automaticamente.<\/p><p>I dati forniti direttamente dall\u2019interessato sono tutti i dati personali che siano forniti al Titolare del Trattamento con qualsiasi modalit\u00e0, direttamente dall'interessato. In particolare sono raccolti e trattati i seguenti dati personali:<br>- Nominativo, email<\/p><p>\u00a0<\/p><p><strong><em>BASE GIURIDICA E FINALITA\u2019 DEL TRATTAMENTO<\/em><\/strong><\/p><p>I dati sono trattati esclusivamente per le finalit\u00e0 per le quali sono raccolti, come di seguito descritte.<\/p><p>Utilizziamo i dati forniti dagli interessati per:<\/p><ul><li>Risposndere alle richieste del cliente dal form contatti<\/li><\/ul><p>Il conferimento dei dati elencati nella sezione \u201cDati Raccolti\u201d per le finalit\u00e0 di cui ai punti n. \u00e8 obbligatorio per consentire all'utente di accedere al servizio. Per tale ragione il consenso \u00e8 obbligatorio e l\u2019eventuale rifiuto al trattamento ovvero il mancato, inesatto o parziale conferimento dei dati potrebbe avere come conseguenza l\u2019impossibilit\u00e0 di una corretta erogazione del servizio.<\/p><p>E' in ogni caso esclusa la diffusione e il trasferimento dei dati al di fuori dello spazio UE.<\/p><p><strong><em>REVOCA DEL CONSENSO<\/em><\/strong><\/p><p>L'interessato pu\u00f2 revocare il proprio consenso alla ricezione di comunicazioni promozionali e commerciali immediatamente, inviando richiesta all'indirizzo email info@profilatibanti.eu<\/p><p><strong><em>MODALITA\u2019 DEL TRATTAMENTO<\/em><\/strong><\/p><p>I dati personali sono trattati con strumenti automatizzati per il tempo strettamente necessario a conseguire gli scopi per cui sono stati raccolti, prevedendo in ogni caso la verifica annuale dei dati conservati al fine di cancellare quelli ritenuti obsoleti, salvo che la legge non preveda obblighi di archiviazione.<\/p><p>Il trattamento dei dati avviene di norma presso la sede della societ\u00e0 Profilati Banti srl, da personale o collaboratori esterni debitamente designati quali responsabili del trattamento. L\u2019elenco completo dei responsabili del trattamento e degli Incaricati al trattamento dei dati personali pu\u00f2 essere richiesto inviando apposita richiesta all\u2019indirizzo email info@profilatibanti.eu<\/p><p>Specifiche misure di sicurezza sono osservate per prevenire la perdita dei dati, usi illeciti o non corretti ed accessi non autorizzati.<\/p><p><strong><em>DIRITTI DELL\u2019INTERESSATO<\/em><\/strong><\/p><p>Ai sensi dell\u2019art. 7 del Codice della Privacy e dell'art. 13 GDPR ciascun utente ha diritto di ottenere la conferma dell\u2019esistenza o meno dei suoi dati personali, anche se non ancora registrati, e la loro comunicazione in forma intellegibile.<\/p><p>In particolare, l\u2019interessato ha diritto di ottenere da Profilati Banti srl l\u2019indicazione:<\/p><ol><li>dell\u2019origine dei dati personali;<\/li><li>della finalit\u00e0 e delle modalit\u00e0 di trattamento;<\/li><li>della logica applicata in caso di trattamento effettuato con l\u2019ausilio di strumenti elettronici\/informatici;<\/li><li>gli estremi identificativi del titolare, dei responsabili e delrappresentante designato;<\/li><li>dei soggetti e delle categorie di soggetti ai quali i dati possono esserecomunicati o che possono venirne a conoscenza in qualit\u00e0 di rappresentante designato nel territorio dello Stato, di responsabili o incaricati.<\/li><\/ol><p>Inoltre l\u2019interessato ha diritto di ottenere da Profilati Banti srl<\/p><ol><li>l\u2019aggiornamento, la rettificazione ovvero l\u2019integrazione dei propri dati;<\/li><li>la cancellazione, la trasformazione in forma anonima o il blocco dei dati trattati in violazione di legge;<\/li><li>l'accesso ai propri dati e cio\u00e8 la conferma che sia o meno in corso un trattamento didati personali che lo riguardano;<\/li><li>la limitazione del trattamento,<\/li><li>la portabilit\u00e0 del dato, cio\u00e8 il diritto di ricevere in formato strutturato i dati personali che lo riguardano;<\/li><li>diritto di reclamo all'Autorit\u00e0 di controllo.<\/li><\/ol><p>Infine l\u2019interessato ha il diritto di opporsi, in tutto o in parte, per motivi legittimi al trattamento dei dati personali che lo riguardano, ancorch\u00e9 pertinenti allo scopo della raccolta. In particolare l'interessato ha il diritto di opporsi al trattamento di dati personali che lo riguardano ai fini di invio di materiale pubblicitario commerciale o di vendita diretta o per il compimento di ricerche di mercato o di comunicazione commerciale. Le richieste di cui ai punti precedenti dovranno essere inviate via email all\u2019indirizzo info@profilatibanti.eu<\/p><p><strong><em>AGGIORNAMENTI E MODIFICHE<\/em><\/strong><\/p><p>Profilati Banti srl si riserva il diritto di modificare, integrare o aggiornare periodicamente la presente Informativa in ossequio alla normativa applicabile o ai provvedimenti adottati dal Garante per la Protezione dei dati personali.<\/p><p>Le suddette modifiche o integrazioni saranno portate a conoscenza degli interessati mediante link alla pagina di Privacy Policy presente nel sito web e saranno comunicate direttamente agli interessati a mezzo email.<\/p><p>Invitiamo gli utenti a prendere visione della Privacy Policy con regolarit\u00e0, per verificare l\u2019Informativa aggiornata e decidere se continuare o meno ad usufruire dei servizi offerti.<\/p>\t\t<\/div>\r\n\r\n\t\t\n\t\t\t\t<\/div><!-- .dslc-module -->\n\t\t<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>PRIVACY POLICYLa presente informativa viene resa in ossequio all&#8217;art. 13 del Regolamento 2016\/679 (GDPR), ai sensi dell&#8217;art. 13 del d.lgs. n. 196\/2003 (Codice in materia di protezione dei dati personali) agli utenti che accedono al sito web https:\/\/banti.it ed \u00e8 relativa a tutti i dati personali trattati secondo le modalit\u00e0 di seguito indicate.IL TITOLARE DEL [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Privacy Policy - Profilati Banti srl<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/banti.it\/it\/privacy-policy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy - Profilati Banti srl\" \/>\n<meta property=\"og:description\" content=\"PRIVACY POLICYLa presente informativa viene resa in ossequio all&#039;art. 13 del Regolamento 2016\/679 (GDPR), ai sensi dell&#039;art. 13 del d.lgs. n. 196\/2003 (Codice in materia di protezione dei dati personali) agli utenti che accedono al sito web https:\/\/banti.it ed \u00e8 relativa a tutti i dati personali trattati secondo le modalit\u00e0 di seguito indicate.IL TITOLARE DEL [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/banti.it\/it\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Profilati Banti srl\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-24T09:08:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/banti.it\/it\/privacy-policy\/\",\"url\":\"https:\/\/banti.it\/it\/privacy-policy\/\",\"name\":\"Privacy Policy - Profilati Banti srl\",\"isPartOf\":{\"@id\":\"https:\/\/banti.it\/it\/#website\"},\"datePublished\":\"2020-11-30T22:02:07+00:00\",\"dateModified\":\"2021-04-24T09:08:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/banti.it\/it\/privacy-policy\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/banti.it\/it\/privacy-policy\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/banti.it\/it\/privacy-policy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/banti.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/banti.it\/it\/#website\",\"url\":\"https:\/\/banti.it\/it\/\",\"name\":\"Profilati B_anti\",\"description\":\"Profili d&#039;autore\",\"publisher\":{\"@id\":\"https:\/\/banti.it\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/banti.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/banti.it\/it\/#organization\",\"name\":\"Banti srl\",\"url\":\"https:\/\/banti.it\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/banti.it\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/banti.it\/wp-content\/uploads\/2020\/12\/cropped-logo.png\",\"contentUrl\":\"https:\/\/banti.it\/wp-content\/uploads\/2020\/12\/cropped-logo.png\",\"width\":450,\"height\":185,\"caption\":\"Banti srl\"},\"image\":{\"@id\":\"https:\/\/banti.it\/it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy Policy - Profilati Banti srl","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/banti.it\/it\/privacy-policy\/","og_locale":"it_IT","og_type":"article","og_title":"Privacy Policy - Profilati Banti srl","og_description":"PRIVACY POLICYLa presente informativa viene resa in ossequio all'art. 13 del Regolamento 2016\/679 (GDPR), ai sensi dell'art. 13 del d.lgs. n. 196\/2003 (Codice in materia di protezione dei dati personali) agli utenti che accedono al sito web https:\/\/banti.it ed \u00e8 relativa a tutti i dati personali trattati secondo le modalit\u00e0 di seguito indicate.IL TITOLARE DEL [&hellip;]","og_url":"https:\/\/banti.it\/it\/privacy-policy\/","og_site_name":"Profilati Banti srl","article_modified_time":"2021-04-24T09:08:13+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/banti.it\/it\/privacy-policy\/","url":"https:\/\/banti.it\/it\/privacy-policy\/","name":"Privacy Policy - Profilati Banti srl","isPartOf":{"@id":"https:\/\/banti.it\/it\/#website"},"datePublished":"2020-11-30T22:02:07+00:00","dateModified":"2021-04-24T09:08:13+00:00","breadcrumb":{"@id":"https:\/\/banti.it\/it\/privacy-policy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/banti.it\/it\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/banti.it\/it\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/banti.it\/it\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy"}]},{"@type":"WebSite","@id":"https:\/\/banti.it\/it\/#website","url":"https:\/\/banti.it\/it\/","name":"Profilati B_anti","description":"Profili d&#039;autore","publisher":{"@id":"https:\/\/banti.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/banti.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/banti.it\/it\/#organization","name":"Banti srl","url":"https:\/\/banti.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/banti.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/banti.it\/wp-content\/uploads\/2020\/12\/cropped-logo.png","contentUrl":"https:\/\/banti.it\/wp-content\/uploads\/2020\/12\/cropped-logo.png","width":450,"height":185,"caption":"Banti srl"},"image":{"@id":"https:\/\/banti.it\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/banti.it\/it\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/banti.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/banti.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/banti.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/banti.it\/it\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":2,"href":"https:\/\/banti.it\/it\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":455,"href":"https:\/\/banti.it\/it\/wp-json\/wp\/v2\/pages\/3\/revisions\/455"}],"wp:attachment":[{"href":"https:\/\/banti.it\/it\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}